{"id":69505,"date":"2026-09-02T08:39:53","date_gmt":"2026-09-02T12:39:53","guid":{"rendered":"https:\/\/www.hampstead.qc.ca\/?post_type=events&#038;p=69505"},"modified":"2026-09-02T09:03:16","modified_gmt":"2026-09-02T13:03:16","slug":"les-chiens-en-fete-a-la-piscine-de-hampstead","status":"publish","type":"events","link":"https:\/\/www.hampstead.qc.ca\/fr\/events\/les-chiens-en-fete-a-la-piscine-de-hampstead\/","title":{"rendered":"Les chiens en f\u00eate \u00e0 la piscine de Hampstead"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-69504 size-full\" src=\"https:\/\/www.hampstead.qc.ca\/wp-content\/uploads\/2026\/09\/Dog-Pool-Pawty.png\" alt=\"\" width=\"631\" height=\"961\" srcset=\"https:\/\/www.hampstead.qc.ca\/wp-content\/uploads\/2026\/09\/Dog-Pool-Pawty.png 631w, https:\/\/www.hampstead.qc.ca\/wp-content\/uploads\/2026\/09\/Dog-Pool-Pawty-197x300.png 197w\" sizes=\"(max-width: 631px) 100vw, 631px\" \/><\/p>\n<p><span style=\"font-size: 1.6rem;\">Offrez \u00e0 votre fid\u00e8le compagnon une derni\u00e8re baignade avant la fermeture de la saison!<\/span><\/p>\n<div>\n<p>Le 22 septembre, la Ville de Hampstead invite les r\u00e9sidents et leur chien \u00e0 participer \u00e0 la populaire activit\u00e9 Les chiens en f\u00eate \u00e0 la piscine de Hampstead. Profitez d&rsquo;un moment unique en compagnie de votre animal alors qu&rsquo;il pourra courir, jouer et se rafra\u00eechir dans la piscine municipale en compagnie d&rsquo;autres amis \u00e0 quatre pattes.<\/p>\n<p>L&rsquo;activit\u00e9 est gratuite pour les d\u00e9tenteurs d&rsquo;un abonnement saisonnier \u00e0 la piscine.<\/p>\n<p>Les propri\u00e9taires doivent pr\u00e9senter une preuve \u00e0 jour de vaccination contre la rage.<\/p>\n<p>Pour les d\u00e9tails et l&rsquo;inscription, communiquez avec le Service des parcs et loisirs au 514 369-8200, poste 2, ou \u00e9crivez \u00e0 <a href=\"mailto: recreation@hampstead.qc.ca\">recreation@hampstead.qc.ca.<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Offrez \u00e0 votre fid\u00e8le compagnon une derni\u00e8re baignade avant la fermeture de la saison! Le 22 septembre, la Ville de Hampstead invite les r\u00e9sidents et leur chien \u00e0 participer \u00e0 la populaire activit\u00e9 Les chiens en f\u00eate \u00e0 la piscine de Hampstead. Profitez d&rsquo;un moment unique en compagnie de votre animal alors qu&rsquo;il pourra courir, jouer et se rafra\u00eechir dans la piscine municipale en compagnie d&rsquo;autres amis \u00e0 quatre pattes. L&rsquo;activit\u00e9 est gratuite pour les d\u00e9tenteurs d&rsquo;un abonnement saisonnier \u00e0 la piscine. Les propri\u00e9taires doivent pr\u00e9senter une preuve \u00e0 jour de vaccination contre la rage. Pour les d\u00e9tails et l&rsquo;inscription,<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","event_type":[],"class_list":["post-69505","events","type-events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hampstead.qc.ca\/fr\/wp-json\/wp\/v2\/events\/69505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hampstead.qc.ca\/fr\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/www.hampstead.qc.ca\/fr\/wp-json\/wp\/v2\/types\/events"}],"wp:attachment":[{"href":"https:\/\/www.hampstead.qc.ca\/fr\/wp-json\/wp\/v2\/media?parent=69505"}],"wp:term":[{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/www.hampstead.qc.ca\/fr\/wp-json\/wp\/v2\/event_type?post=69505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}